{"id":4121,"date":"2015-02-16T05:43:05","date_gmt":"2015-02-16T04:43:05","guid":{"rendered":"https:\/\/life-is-a-trip.com\/?p=4121"},"modified":"2019-02-26T11:52:04","modified_gmt":"2019-02-26T10:52:04","slug":"africa-travel","status":"publish","type":"post","link":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/","title":{"rendered":"Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia"},"content":{"rendered":"<p>After all the words (in German) and all the pictures, here come the first moving\u00a0images from my Africa travel project #LiaTgoesAfrica. In part 1 you&#8217;ll see Namibia, Botswana, Zimbabwe and a first impression of Zambia. Part 2 of the Africa travel video is still in the edit &#8211; stay tuned!<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/twmhqF7uDwo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>After all the words (in German) and all the pictures, here come the first moving\u00a0images from my Africa travel project #LiaTgoesAfrica. In part 1 you&#8217;ll see Namibia, Botswana, Zimbabwe and a first impression of Zambia. Part 2 of the Africa travel video is still in &#8230; <a title=\"Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia\" class=\"read-more\" href=\"https:\/\/life-is-a-trip.com\/en\/africa-travel\/\" aria-label=\"Read more about Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia\"> <\/a><\/p>\n","protected":false},"author":1,"featured_media":4018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[684,683,239,2797,2798],"tags":[],"class_list":["post-4121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-botswana","category-namibia","category-travel-videos","category-zambia","category-zimbabwe","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Africa travel - Namibia, Botswana, Zimbabwe, Zambia - LIFE IS A TRIP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/life-is-a-trip.com\/en\/africa-travel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Africa travel - Namibia, Botswana, Zimbabwe, Zambia - LIFE IS A TRIP\" \/>\n<meta property=\"og:description\" content=\"After all the words (in German) and all the pictures, here come the first moving\u00a0images from my Africa travel project #LiaTgoesAfrica. In part 1 you&#8217;ll see Namibia, Botswana, Zimbabwe and a first impression of Zambia. Part 2 of the Africa travel video is still in ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/life-is-a-trip.com\/en\/africa-travel\/\" \/>\n<meta property=\"og:site_name\" content=\"LIFE IS A TRIP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LifeIsATripCom\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/LifeIsATripCom\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-16T04:43:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-26T10:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Buch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LifeIsATripCOM\" \/>\n<meta name=\"twitter:site\" content=\"@LifeIsATripCOM\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Buch\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/\"},\"author\":{\"name\":\"Marco Buch\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/#\\\/schema\\\/person\\\/83efd23a4e95d766f3dd96cde15fa7ec\"},\"headline\":\"Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia\",\"datePublished\":\"2015-02-16T04:43:05+00:00\",\"dateModified\":\"2019-02-26T10:52:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/\"},\"wordCount\":57,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/#\\\/schema\\\/person\\\/83efd23a4e95d766f3dd96cde15fa7ec\"},\"image\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Collage-21.jpg\",\"articleSection\":[\"Botswana\",\"Namibia\",\"Travel Videos\",\"Zambia\",\"Zimbabwe\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/\",\"url\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/\",\"name\":\"Africa travel - Namibia, Botswana, Zimbabwe, Zambia - LIFE IS A TRIP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Collage-21.jpg\",\"datePublished\":\"2015-02-16T04:43:05+00:00\",\"dateModified\":\"2019-02-26T10:52:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Collage-21.jpg\",\"contentUrl\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Collage-21.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/africa-travel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/life-is-a-trip.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/#website\",\"url\":\"https:\\\/\\\/life-is-a-trip.com\\\/\",\"name\":\"LIFE IS A TRIP\",\"description\":\"Campfire Storytelling 2.0\",\"publisher\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/#\\\/schema\\\/person\\\/83efd23a4e95d766f3dd96cde15fa7ec\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/life-is-a-trip.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/#\\\/schema\\\/person\\\/83efd23a4e95d766f3dd96cde15fa7ec\",\"name\":\"Marco Buch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Marco-Buch.png\",\"url\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Marco-Buch.png\",\"contentUrl\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Marco-Buch.png\",\"width\":702,\"height\":702,\"caption\":\"Marco Buch\"},\"logo\":{\"@id\":\"https:\\\/\\\/life-is-a-trip.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Marco-Buch.png\"},\"description\":\"Marco Buch ist Filmschaffender, Buchautor, Blogger, Weltreisender. Er ist ein neugieriger Mensch und viel unterwegs. Marco hat in \u00fcber 130 unterschiedlichen Jobs gearbeitet und 77 L\u00e4nder dieser Welt bereist. Er liebt es, Erfahrungen zu sammeln und sp\u00e4ter Anderen davon zu erz\u00e4hlen. Mit 'Life is a Trip' m\u00f6chte er die Tradition der Lagerfeuergeschichten ins digitale Zeitalter hin\u00fcberretten. Marco nimmt sich selbst nicht so wahnsinnig ernst und denkt, die Welt k\u00f6nnte eine bessere sein, wenn andere diesem Beispiel folgen w\u00fcrden.\",\"sameAs\":[\"https:\\\/\\\/life-is-a-trip.com\",\"https:\\\/\\\/www.facebook.com\\\/LifeIsATripCom\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lifeisatripcom\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/LifeIsATripCOM\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Africa travel - Namibia, Botswana, Zimbabwe, Zambia - LIFE IS A TRIP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/","og_locale":"en_US","og_type":"article","og_title":"Africa travel - Namibia, Botswana, Zimbabwe, Zambia - LIFE IS A TRIP","og_description":"After all the words (in German) and all the pictures, here come the first moving\u00a0images from my Africa travel project #LiaTgoesAfrica. In part 1 you&#8217;ll see Namibia, Botswana, Zimbabwe and a first impression of Zambia. Part 2 of the Africa travel video is still in ...","og_url":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/","og_site_name":"LIFE IS A TRIP","article_publisher":"https:\/\/www.facebook.com\/LifeIsATripCom\/","article_author":"https:\/\/www.facebook.com\/LifeIsATripCom\/","article_published_time":"2015-02-16T04:43:05+00:00","article_modified_time":"2019-02-26T10:52:04+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg","type":"image\/jpeg"}],"author":"Marco Buch","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/LifeIsATripCOM","twitter_site":"@LifeIsATripCOM","twitter_misc":{"Written by":"Marco Buch"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#article","isPartOf":{"@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/"},"author":{"name":"Marco Buch","@id":"https:\/\/life-is-a-trip.com\/#\/schema\/person\/83efd23a4e95d766f3dd96cde15fa7ec"},"headline":"Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia","datePublished":"2015-02-16T04:43:05+00:00","dateModified":"2019-02-26T10:52:04+00:00","mainEntityOfPage":{"@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/"},"wordCount":57,"commentCount":0,"publisher":{"@id":"https:\/\/life-is-a-trip.com\/#\/schema\/person\/83efd23a4e95d766f3dd96cde15fa7ec"},"image":{"@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#primaryimage"},"thumbnailUrl":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg","articleSection":["Botswana","Namibia","Travel Videos","Zambia","Zimbabwe"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/life-is-a-trip.com\/en\/africa-travel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/","url":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/","name":"Africa travel - Namibia, Botswana, Zimbabwe, Zambia - LIFE IS A TRIP","isPartOf":{"@id":"https:\/\/life-is-a-trip.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#primaryimage"},"image":{"@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#primaryimage"},"thumbnailUrl":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg","datePublished":"2015-02-16T04:43:05+00:00","dateModified":"2019-02-26T10:52:04+00:00","breadcrumb":{"@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/life-is-a-trip.com\/en\/africa-travel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#primaryimage","url":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg","contentUrl":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/life-is-a-trip.com\/en\/africa-travel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/life-is-a-trip.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Africa travel &#8211; Namibia, Botswana, Zimbabwe, Zambia"}]},{"@type":"WebSite","@id":"https:\/\/life-is-a-trip.com\/#website","url":"https:\/\/life-is-a-trip.com\/","name":"LIFE IS A TRIP","description":"Campfire Storytelling 2.0","publisher":{"@id":"https:\/\/life-is-a-trip.com\/#\/schema\/person\/83efd23a4e95d766f3dd96cde15fa7ec"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/life-is-a-trip.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/life-is-a-trip.com\/#\/schema\/person\/83efd23a4e95d766f3dd96cde15fa7ec","name":"Marco Buch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2018\/05\/Marco-Buch.png","url":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2018\/05\/Marco-Buch.png","contentUrl":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2018\/05\/Marco-Buch.png","width":702,"height":702,"caption":"Marco Buch"},"logo":{"@id":"https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2018\/05\/Marco-Buch.png"},"description":"Marco Buch ist Filmschaffender, Buchautor, Blogger, Weltreisender. Er ist ein neugieriger Mensch und viel unterwegs. Marco hat in \u00fcber 130 unterschiedlichen Jobs gearbeitet und 77 L\u00e4nder dieser Welt bereist. Er liebt es, Erfahrungen zu sammeln und sp\u00e4ter Anderen davon zu erz\u00e4hlen. Mit 'Life is a Trip' m\u00f6chte er die Tradition der Lagerfeuergeschichten ins digitale Zeitalter hin\u00fcberretten. Marco nimmt sich selbst nicht so wahnsinnig ernst und denkt, die Welt k\u00f6nnte eine bessere sein, wenn andere diesem Beispiel folgen w\u00fcrden.","sameAs":["https:\/\/life-is-a-trip.com","https:\/\/www.facebook.com\/LifeIsATripCom\/","https:\/\/www.instagram.com\/lifeisatripcom\/","https:\/\/x.com\/https:\/\/twitter.com\/LifeIsATripCOM"]}]}},"uagb_featured_image_src":{"full":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg",1024,768,false],"thumbnail":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21-770x578.jpg",770,578,true],"medium":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21-770x578.jpg",770,578,true],"medium_large":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21-768x576.jpg",768,576,true],"large":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg",1024,768,false],"wysija-newsletters-max":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21-600x450.jpg",600,450,true],"1536x1536":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg",1024,768,false],"2048x2048":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg",1024,768,false],"mailpoet_newsletter_max":["https:\/\/life-is-a-trip.com\/wp-content\/uploads\/2015\/02\/Collage-21.jpg",1024,768,false]},"uagb_author_info":{"display_name":"Marco Buch","author_link":"https:\/\/life-is-a-trip.com\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"After all the words (in German) and all the pictures, here come the first moving\u00a0images from my Africa travel project #LiaTgoesAfrica. In part 1 you&#8217;ll see Namibia, Botswana, Zimbabwe and a first impression of Zambia. Part 2 of the Africa travel video is still in ...","_links":{"self":[{"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/posts\/4121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/comments?post=4121"}],"version-history":[{"count":0,"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/posts\/4121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/media\/4018"}],"wp:attachment":[{"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/media?parent=4121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/categories?post=4121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/life-is-a-trip.com\/en\/wp-json\/wp\/v2\/tags?post=4121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}